{"id":13843,"date":"2024-06-17T10:51:03","date_gmt":"2024-06-17T10:51:03","guid":{"rendered":"https:\/\/liacc.fe.up.pt\/liaccwp\/?post_type=_people&#038;p=13843"},"modified":"2024-07-26T17:46:46","modified_gmt":"2024-07-26T17:46:46","slug":"joao-duarte","status":"publish","type":"_people","link":"https:\/\/liacc.fe.up.pt\/liaccwp\/_people\/joao-duarte\/","title":{"rendered":"Jo\u00e3o Duarte"},"featured_media":0,"template":"","class_list":["post-13843","_people","type-_people","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/liacc.fe.up.pt\/liaccwp\/wp-json\/wp\/v2\/_people\/13843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liacc.fe.up.pt\/liaccwp\/wp-json\/wp\/v2\/_people"}],"about":[{"href":"https:\/\/liacc.fe.up.pt\/liaccwp\/wp-json\/wp\/v2\/types\/_people"}],"version-history":[{"count":2,"href":"https:\/\/liacc.fe.up.pt\/liaccwp\/wp-json\/wp\/v2\/_people\/13843\/revisions"}],"predecessor-version":[{"id":14041,"href":"https:\/\/liacc.fe.up.pt\/liaccwp\/wp-json\/wp\/v2\/_people\/13843\/revisions\/14041"}],"wp:attachment":[{"href":"https:\/\/liacc.fe.up.pt\/liaccwp\/wp-json\/wp\/v2\/media?parent=13843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}